{"id":6582,"date":"2026-06-25T10:11:54","date_gmt":"2026-06-25T10:11:54","guid":{"rendered":"https:\/\/laboratorium.eus\/eguzki-eklipseen-sekretuak-ezagutzeko-hitzaldia-antolatu-du-laboratorium-museoak-uztailaren-3rako\/"},"modified":"2026-06-26T10:39:50","modified_gmt":"2026-06-26T10:39:50","slug":"eguzki-eklipseen-sekretuak-ezagutzeko-hitzaldia-antolatu-du-laboratorium-museoak-uztailaren-3rako","status":"publish","type":"post","link":"https:\/\/laboratorium.eus\/es\/eguzki-eklipseen-sekretuak-ezagutzeko-hitzaldia-antolatu-du-laboratorium-museoak-uztailaren-3rako\/","title":{"rendered":"El Museo Laboratorium organiza una conferencia para descubrir los secretos de los eclipses solares, el pr\u00f3ximo 3 de julio"},"content":{"rendered":"<p class=\"\"><strong>Josu Gonz\u00e1lez (Ilatargi Elkartea) explicar\u00e1 en Bergara la historia y la ciencia de los eclipses, as\u00ed como las claves para observar el fen\u00f3meno astron\u00f3mico que tendr\u00e1 lugar el 12 de agosto<\/strong><\/p>\n<p class=\"\">Dentro del programa ZTB (Ciencia, Tecnolog\u00eda e Innovaci\u00f3n), el Museo Laboratorium organiza una conferencia de divulgaci\u00f3n sobre los eclipses para el pr\u00f3ximo 3 de julio. La sesi\u00f3n tendr\u00e1 lugar a las 19:00 horas en el Seminarixoa de Bergara, se impartir\u00e1 en euskera y est\u00e1 dirigida a todo el p\u00fablico. <\/p>\n<p class=\"\">Con motivo del eclipse solar total que tendr\u00e1 lugar el pr\u00f3ximo 12 de agosto, Josu Gonz\u00e1lez, miembro de la asociaci\u00f3n astron\u00f3mica Ilatargi Elkartea, ofrecer\u00e1 una charla para profundizar en este espectacular fen\u00f3meno astron\u00f3mico. Bajo el t\u00edtulo Eklipseak: astroak ezkutaketan jolasten (\u00abLos eclipses: los astros jugando al escondite\u00bb), la conferencia explicar\u00e1 de forma clara y cercana qu\u00e9 es un eclipse, por qu\u00e9 se produce y c\u00f3mo lo han entendido e interpretado las distintas culturas a lo largo de la historia.<\/p>\n<p class=\"\">La sesi\u00f3n partir\u00e1 de la visi\u00f3n de las civilizaciones antiguas para trazar un recorrido hasta nuestros d\u00edas. A trav\u00e9s de un relato divulgativo y visual, se mostrar\u00e1 c\u00f3mo estos fen\u00f3menos, que en su d\u00eda despertaban miedo y creencias, se convirtieron en fuente de conocimiento cient\u00edfico. Tambi\u00e9n se abordar\u00e1 la importancia que los eclipses han tenido en la historia de la ciencia.  <\/p>\n<p class=\"\">La parte final de la conferencia tendr\u00e1 un enfoque m\u00e1s pr\u00e1ctico, de cara al eclipse total del 12 de agosto. Los asistentes podr\u00e1n conocer c\u00f3mo observarlo de forma segura, cu\u00e1les ser\u00e1n los mejores puntos de observaci\u00f3n y qu\u00e9 podr\u00e1n ver durante el fen\u00f3meno. <\/p>\n<p class=\"\">Laboratorium Museoa ha organizado esta conferencia dentro de un programa m\u00e1s amplio dedicado a los eclipses, que incluye otras iniciativas y una exposici\u00f3n desarrolladas en las \u00faltimas semanas. El objetivo es reforzar la divulgaci\u00f3n en torno al eclipse solar y acercar el fen\u00f3meno al p\u00fablico de manera comprensible y cercana. Esta actividad se enmarca en el programa que ZTB desarrolla a lo largo de todo el a\u00f1o.  <\/p>\n<p class=\"\">Al finalizar la charla, el Museo Laboratorium distribuir\u00e1 gratuitamente gafas homologadas para la observaci\u00f3n segura del eclipse del 12 de agosto, con el objetivo de facilitar que la ciudadan\u00eda pueda disfrutar de este fen\u00f3meno astron\u00f3mico excepcional en las mejores condiciones y con todas las garant\u00edas de seguridad. Adem\u00e1s, aquellas personas que no puedan asistir a la sesi\u00f3n o que deseen adquirir m\u00e1s unidades, podr\u00e1n comprarlas posteriormente en el propio Museo Laboratorium por un precio simb\u00f3lico de un euro. <\/p>\n<p class=\"last-child\">La entrada es gratuita, pero dado que las plazas son limitadas, se recomienda inscribirse con antelaci\u00f3n. Para ello, las personas interesadas pueden hacerlo a trav\u00e9s del <a href=\"https:\/\/laboratorium.eus\/es\/event\/eclipses-las-estrellas-jugando-al-escondite\/\">formulario disponible en la web de Laboratorium Museoa,<\/a> llamando al 943 769 003 o escribiendo a <a href=\"mailto:laboratorium@bergara.eus?subject=&#038;body=\" target=\"_blank\" rel=\"noopener\">laboratorium@bergara.eus.<\/a> <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6578\" src=\"https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede-240x300.jpg\" alt=\"\" width=\"899\" height=\"1124\" srcset=\"https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede-240x300.jpg 240w, https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede-819x1024.jpg 819w, https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede-768x960.jpg 768w, https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede-600x750.jpg 600w, https:\/\/laboratorium.eus\/wp-content\/uploads\/2026\/06\/c1d57534-1866-562d-c8a5-478712048ede.jpg 1080w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/p>\n<h2 class=\"mcePastedContent\"><strong>Ponente<\/strong><\/h2>\n<p class=\"\">Josu Gonz\u00e1lez es miembro de Ilatargi Talde Astronomikoa desde 2018 y se dedica a la divulgaci\u00f3n de la astronom\u00eda. Ilatargi ofrece sesiones de observaci\u00f3n y actividades did\u00e1cticas con el objetivo de acercar el conocimiento astron\u00f3mico a la ciudadan\u00eda. <\/p>\n<h2 class=\"mcePastedContent\"><strong>Detalles del evento<\/strong><\/h2>\n<h2><\/h2>\n<ul class=\"last-child\">\n<li>\n<p class=\"mcePastedContent\">Fecha: 3 de julio de 2026<\/p>\n<\/li>\n<li>\n<p class=\"mcePastedContent\">Hora: 19:00<\/p>\n<\/li>\n<li>\n<p class=\"mcePastedContent\">Lugar: Seminarixoa (Bergara)<\/p>\n<\/li>\n<li>\n<p class=\"mcePastedContent\">Idioma: vasco<\/p>\n<\/li>\n<li>\n<p class=\"mcePastedContent\">Ponente: Josu Gonz\u00e1lez (Ilatargi Elkartea)<\/p>\n<\/li>\n<li>\n<p class=\"mcePastedContent\">Entrada gratuita<\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Josu Gonz\u00e1lez (Ilatargi Elkartea) explicar\u00e1 en Bergara la historia y la ciencia de los eclipses, as\u00ed como las claves para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_eb_data_table":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[37],"tags":[],"class_list":["post-6582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-charla"],"_links":{"self":[{"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/posts\/6582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/comments?post=6582"}],"version-history":[{"count":1,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/posts\/6582\/revisions"}],"predecessor-version":[{"id":6585,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/posts\/6582\/revisions\/6585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/media\/6583"}],"wp:attachment":[{"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/media?parent=6582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/categories?post=6582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laboratorium.eus\/es\/wp-json\/wp\/v2\/tags?post=6582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}